{"id":25347,"date":"2019-11-19T00:00:00","date_gmt":"2019-11-18T23:00:00","guid":{"rendered":"https:\/\/mm-live.digilicious.cloud\/news\/mmgroup\/mm-karton-ist-teil-der-4evergreen-allianz\/"},"modified":"2025-04-04T11:52:59","modified_gmt":"2025-04-04T09:52:59","slug":"mm-karton-ist-teil-der-4evergreen-allianz","status":"publish","type":"post","link":"https:\/\/mm.group\/de\/news\/board-paper\/mm-karton-ist-teil-der-4evergreen-allianz\/","title":{"rendered":"MM Karton ist Teil der 4evergreen-Allianz"},"content":{"rendered":"<section class=\"mm-wrapper-new\">Ziel der neu gebildeten Allianz ist es, den Beitrag der faserbasierten Verpackungen zu einer nachhaltigen Kreislaufwirtschaft, die die Auswirkungen auf Klima und Umwelt minimiert, auszubauen. Die Allianz soll die Vorteile von faserbasierten Verpackungsmaterialien als alternative L\u00f6sungen verst\u00e4rkt kommunizieren. Die Allianz wird zudem f\u00fcr EU-weit harmonisierte Richtlinien f\u00fcr Produktdesign eintreten, die die Recyclingf\u00e4higkeit erleichtern, und die Optimierung von Sammelsystemen sowie geeigneter Recyclinginfrastrukturen und -technologien unterst\u00fctzen.4evergreen vernetzt Papier- und Kartonhersteller, Faltschachtelhersteller, Markeninhaber und H\u00e4ndler, Technologie- und Materiallieferanten sowie die Sammel-, Sortier- und Recyclingbranche. Zu den Mitgliedern neben der Mayr-Melnhof Gruppe z\u00e4hlen Mars, Nestl\u00e9, Danone und Tetrapak.<\/p>\n<p>Die gegenw\u00e4rtigen Bedingungen, die Verbraucherstimmung und die am 2. Juli 2019 in Kraft getretene Einweg-Plastikrichtlinie haben Unternehmen dazu veranlasst, die Entwicklung alternativer Verpackungen zu beschleunigen. Materialien wie faserbasierte Verpackungen und neue Designs sollen es den Verbrauchern erleichtern, klimafreundlichere Entscheidungen zu treffen. Aufgrund ihrer geringen CO<sub>2<\/sub>-Werte sowie ihrer Eigenschaften, erneuerbar, recycelbar und biologisch abbaubar zu sein, k\u00f6nnen faserbasierte Verpackungen eine entscheidende Rolle bei der F\u00f6rderung der Kreislaufwirtschaft spielen.<\/p>\n<div class=\"row\">\n<div>\n<div class=\"magazine-print-teaser\">\n<div class=\"row\">\n<figure><img loading=\"lazy\" decoding=\"async\" class=\"img-full-width\" src=\"https:\/\/mm.group\/wp-content\/uploads\/news-mmboardpaper-content-csm_MMK_Unfolded_3_2019_DE_WEB-1_b8f85468b7.webp\" alt=\"\" width=\"420\" height=\"534\" \/><\/figure>\n<div>\n<h2>Diesen sowie viele weitere Artikel finden Sie im Unfolded Printmagazin!<\/h2>\n<div class=\"magazine-print-teaser-download\">\n<p>Download:<\/p>\n<ul class=\"list-unstyled magazine-print-teaser-download-list\">\n<li><a href=\"https:\/\/mm.group\/wp-content\/uploads\/MMK_Unfolded_3_2019_DE_WEB.pdf\" target=\"_blank\" rel=\"noopener\">DE<\/a><\/li>\n<li><a href=\"https:\/\/mm.group\/wp-content\/uploads\/MMK_Unfolded_3_2019_EN_WEB.pdf\" target=\"_blank\" rel=\"noopener\">EN<\/a><\/li>\n<li><a href=\"https:\/\/mm.group\/wp-content\/uploads\/MMK_Unfolded_3_2019_RU_WEB.pdf\" target=\"_blank\" rel=\"noopener\">RU<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Ziel der neu gebildeten Allianz ist es, den Beitrag der faserbasierten Verpackungen zu einer nachhaltigen Kreislaufwirtschaft, die die Auswirkungen auf Klima und Umwelt minimiert, auszubauen. Die Allianz soll die Vorteile von faserbasierten Verpackungsmaterialien als alternative L\u00f6sungen verst\u00e4rkt kommunizieren. Die Allianz wird zudem f\u00fcr EU-weit harmonisierte Richtlinien f\u00fcr Produktdesign eintreten, die die Recyclingf\u00e4higkeit erleichtern, und die &hellip; <a href=\"https:\/\/mm.group\/de\/news\/board-paper\/mm-karton-ist-teil-der-4evergreen-allianz\/\">Continued<\/a><\/p>\n","protected":false},"author":1,"featured_media":23560,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[304],"tags":[],"category-news":[320,324],"class_list":["post-25347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-board-paper","category-news-nachhaltigkeit","category-news-unternehmen-werke"],"acf":[],"_links":{"self":[{"href":"https:\/\/mm.group\/de\/wp-json\/wp\/v2\/posts\/25347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mm.group\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mm.group\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mm.group\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mm.group\/de\/wp-json\/wp\/v2\/comments?post=25347"}],"version-history":[{"count":1,"href":"https:\/\/mm.group\/de\/wp-json\/wp\/v2\/posts\/25347\/revisions"}],"predecessor-version":[{"id":40330,"href":"https:\/\/mm.group\/de\/wp-json\/wp\/v2\/posts\/25347\/revisions\/40330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mm.group\/de\/wp-json\/wp\/v2\/media\/23560"}],"wp:attachment":[{"href":"https:\/\/mm.group\/de\/wp-json\/wp\/v2\/media?parent=25347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mm.group\/de\/wp-json\/wp\/v2\/categories?post=25347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mm.group\/de\/wp-json\/wp\/v2\/tags?post=25347"},{"taxonomy":"category-news","embeddable":true,"href":"https:\/\/mm.group\/de\/wp-json\/wp\/v2\/category-news?post=25347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}